{"id":23587,"date":"2018-04-26T15:03:28","date_gmt":"2018-04-26T13:03:28","guid":{"rendered":"http:\/\/www.h-its.org\/?p=23587"},"modified":"2019-03-22T09:42:30","modified_gmt":"2019-03-22T08:42:30","slug":"eroeffnung-eso-supernova","status":"publish","type":"post","link":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/","title":{"rendered":"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Heute wird nach dreij\u00e4hriger Bauzeit das ESO Supernova Planetarium und Besucherzentrum feierlich eingeweiht. Das neue Zentrum am Hauptsitz der Europ\u00e4ischen S\u00fcdsternwarte (ESO) in Garching ist eine Schenkung der Klaus Tschira Stiftung an die ESO. Das hochmoderne astronomische Besucherzentrum soll der \u00d6ffentlichkeit die Faszination und Bedeutung der Astronomie und Astrophysik vermitteln. Die Idee f\u00fcr das Zentrum ist aus einer Kooperation zwischen der ESO und dem Heidelberger Institut f\u00fcr Theoretische Studien (HITS) hervorgegangen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Besucher erwartet in der <a rel=\"noopener noreferrer\" href=\"https:\/\/supernova.eso.org\/germany\/\" target=\"_blank\">ESO Supernova<\/a> eine interaktive astronomische Ausstellung sowie das gr\u00f6\u00dfte geneigte 360-Grad-Planetarium in Deutschland, \u00d6sterreich und der Schweiz. Die Planetariumskuppel hat einen Durchmesser von 14 Metern, eine Neigung von 25 Grad und bietet 110 Sitzpl\u00e4tze. Durch die hochmoderne Projektionstechnik haben die Besucherinnen und Besucher im Planetarium den Eindruck, selbst durch das Universum zu reisen. Die Ausstellung mit dem Titel \u201eDas lebendige Universum\u201c behandelt 13 astronomische Themen und erstreckt sich \u00fcber 2.200 Quadratmeter. Eine 255 Meter lange spiralf\u00f6rmige Rampe f\u00fchrt die Besucher durch die Ausstellung. Durch diese Rampe und durch den gl\u00e4sernen Aufzug k\u00f6nnen auch Menschen mit einer Behinderung den Besuch in allen Bereichen der ESO Supernova in vollem Umfang genie\u00dfen. Die Ausstellung informiert au\u00dferdem \u00fcber neueste wissenschaftliche Erkenntnisse der Astronomie und Astrophysik. Das HITS, das von <a rel=\"noopener noreferrer\" href=\"https:\/\/www.klaus-tschira-stiftung.de\/\" target=\"_blank\">Klaus Tschira und seiner Stiftung<\/a> gegr\u00fcndet wurde, hat die Konzeption der Ausstellung wissenschaftlich begleitet und fachliche Expertise beigesteuert. Die HITS-Mitarbeiter der Supernova-Projektgruppe unter der Leitung von <a rel=\"noopener noreferrer\" href=\"http:\/\/www.h-its.org\/de\/forschung\/ain\/mitarbeiter\/\" target=\"_blank\">Dr. Kai Polsterer<\/a> haben speziell f\u00fcr diese Ausstellung interaktive Exponate entwickelt. Mithilfe von Computersimulationen, virtueller Realit\u00e4t und hochmoderner Computergrafiken k\u00f6nnen die Besucher in eine ebenso vielseitige wie faszinierende Themenwelt eintauchen.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.h-its.org\/wp-content\/uploads\/2018\/04\/ann18009a.jpg\"><img decoding=\"async\" src=\"http:\/\/www.h-its.org\/wp-content\/uploads\/2018\/04\/ann18009a-1024x682.jpg\" alt=\"\" class=\"wp-image-30197\" \/><\/a><figcaption><br>Einblick in die Ausstellung \u201cDas lebendige Universum\u201d, die das HITS wissenschaftlich und technisch mitentwickelt hat (Bild: ESO).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Beeindruckend ist auch in 15 Metern H\u00f6he das leuchtende Sternendach \u00fcber dem \u201eWelt-Raum\u201c. Dort erscheinen die 22 Sternbilder der s\u00fcdlichen Hemisph\u00e4re. An der Wand dieses \u201eWelt-Raums\u201c h\u00e4ngt eine 360-Grad Abbildung der Milchstra\u00dfe, die zum Entdecken einl\u00e4dt. \u201eEine gro\u00dfe Leidenschaft unseres Stifters Klaus Tschira war die Astronomie\u201c, sagte Beate Spiegel, Gesch\u00e4ftsf\u00fchrerin der Klaus Tschira Stiftung, \u201emit diesem Projekt wollte er seine Faszination mit der \u00d6ffentlichkeit teilen. Die ESO Supernova ist das letzte Geb\u00e4ude, das er noch selbst auf den Weg bringen konnte, bevor er 2015 verstarb.\u201c Betrieben wird die Supernova von der ESO. Ihre Angebote richten sich an alle Altersgruppen. Der Eintritt ist frei, jedoch m\u00fcssen sich die Besucher vorab online anmelden. F\u00fcr Kinderg\u00e4rten, Grund- und weiterf\u00fchrende Schulen hat das Team der ESO Supernova ein zus\u00e4tzliches Programm zusammengestellt, hierzu z\u00e4hlen spezielle F\u00fchrungen, Planetariumshows und Workshops. Au\u00dferdem bietet die ESO Supernova Fortbildungen f\u00fcr Lehrkr\u00e4fte an.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.h-its.org\/wp-content\/uploads\/2018\/04\/ann15011b.jpg\"><img decoding=\"async\" src=\"http:\/\/www.h-its.org\/wp-content\/uploads\/2018\/04\/ann15011b-1024x512.jpg\" alt=\"\" class=\"wp-image-30196\" \/><\/a><figcaption>Das Geb\u00e4ude der ESO Supernova \u00e4hnelt einem Doppelsternsystem. Ein Doppelsternsystem ist ein astronomisches Ph\u00e4nomen, das unter anderem zu einer thermonukleare Supernovae f\u00fchren kann (Bild: ESO).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ebenso spektakul\u00e4r wie der Inhalt der ESO Supernova ist auch das Design des Geb\u00e4udes. Wie der Name bereits verr\u00e4t, \u00e4hnelt die Form des Zentrums einem engen Doppelsternsystem, bei dem ein Stern Masse von seinem Begleiter abzieht. Dies f\u00fchrt im Weltall dazu, dass der schwerere Stern als Supernova explodiert und dabei so hell erstrahlt wie alle Sterne der Galaxie zusammen. Das Design des eindrucksvollen Geb\u00e4udes ist von Klaus Tschira mit Unterst\u00fctzung des Darmst\u00e4dter Architekturb\u00fcros Bernhardt+Partner konzipiert worden. \u201eKlaus Tschira hatte Freude daran, gemeinsam mit den Architekten an einzigartigen Geb\u00e4udeformen zu arbeiten\u201c, sagte Beate Spiegel, \u201ein Heidelberg stehen beispielsweise bereits das Haus der Astronomie, das einer Spiralgalaxie \u00e4hnelt und das ATC, das einer DNA-Doppelhelix nachempfunden ist.\u201c In ausgew\u00e4hlten F\u00e4llen f\u00f6rdert die Stiftung Architektur f\u00fcr die Wissenschaft. Dies ist neben Bildung, Forschung und Wissenschaftskommunikation der vierte Themenschwerpunkt der Klaus Tschira Stiftung.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.h-its.org\/wp-content\/uploads\/2018\/04\/gravitation2.png\"><img decoding=\"async\" src=\"http:\/\/www.h-its.org\/wp-content\/uploads\/2018\/04\/gravitation2-1024x698.png\" alt=\"\" class=\"wp-image-30198\" \/><\/a><figcaption>Ein Interactive, das am HITS eigens f\u00fcr die Ausstellung in der ESO Supernova entwickelt wurde: Bei dem Spiel \u201cGravity Pong\u201d k\u00f6nnen Besucher und Besucherinnen die M\u00f6glichkeiten von Gravitation kennenlernen (Foto: HITS).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00d6ffnungszeiten ESO Supernova:<\/strong><br>Mittwoch bis Freitag 9:00 bis 17:00 Uhr<br>Samstag und Sonntag 12:00 bis 17:00 Uhr<br>Kostenlose Tickets k\u00f6nnen online gebucht und dann vor Ort bei Ankunft ausgedruckt werden.[\/vc_column_text][vc_empty_space height=&#8220;20&#8243;][vc_column_text]<strong>\u00dcber die Klaus Tschira Stiftung (KTS)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Klaus Tschira Stiftung (KTS) f\u00f6rdert Naturwissenschaften, Mathematik und Informatik und m\u00f6chte zur Wertsch\u00e4tzung dieser F\u00e4cher beitragen. Sie wurde 1995 von dem Physiker und SAP-Mitgr\u00fcnder Klaus Tschira mit privaten Mitteln ins Leben gerufen. Ihre drei F\u00f6rderschwerpunkte sind: Bildung, Forschung und Wissenschaftskommunikation. Das bundesweite Engagement beginnt im Kindergarten und setzt sich in Schulen, Hochschulen und Forschungseinrichtungen fort. Die Stiftung setzt sich f\u00fcr neue Formen der Vermittlung naturwissenschaftlicher Inhalte ein. Weitere Informationen unter: <a href=\"http:\/\/www.klaus-tschira-stiftung.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.klaus-tschira-stiftung.de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pressekontakt KTS:<\/strong><br>Klaus Tschira Stiftung<br>Mara Knapp<br>E-Mail: <a href=\"mailto:mara.knapp@klaus-tschira-stiftung.de\" target=\"_blank\" rel=\"noopener noreferrer\">mara.knapp@klaus-tschira-stiftung.de<\/a><br>Tel.: 06221 533 151<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute wird nach dreij\u00e4hriger Bauzeit das ESO Supernova Planetarium und Besucherzentrum feierlich eingeweiht. Das neue Zentrum am Hauptsitz der Europ\u00e4&#8230;<\/p>\n","protected":false},"author":6,"featured_media":30196,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[95,1329],"hits-research-group":[],"class_list":["post-23587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institutsnews","category-pressemitteilungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet - HITS gGmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet - HITS gGmbH\" \/>\n<meta property=\"og:description\" content=\"Heute wird nach dreij\u00e4hriger Bauzeit das ESO Supernova Planetarium und Besucherzentrum feierlich eingeweiht. Das neue Zentrum am Hauptsitz der Europ\u00e4...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/\" \/>\n<meta property=\"og:site_name\" content=\"HITS gGmbH\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-26T13:03:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-22T08:42:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2018\/04\/ann15011b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lacurie, Isabel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lacurie, Isabel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/\"},\"author\":{\"name\":\"Lacurie, Isabel\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/86aabe0b57e15165f41adaf38c43d078\"},\"headline\":\"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet\",\"datePublished\":\"2018-04-26T13:03:28+00:00\",\"dateModified\":\"2019-03-22T08:42:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/\"},\"wordCount\":798,\"image\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/ann15011b.jpg\",\"articleSection\":[\"Institutsnews\",\"Pressemitteilungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/\",\"name\":\"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet - HITS gGmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/ann15011b.jpg\",\"datePublished\":\"2018-04-26T13:03:28+00:00\",\"dateModified\":\"2019-03-22T08:42:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/86aabe0b57e15165f41adaf38c43d078\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/ann15011b.jpg\",\"contentUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/ann15011b.jpg\",\"width\":1280,\"height\":640,\"caption\":\"The ESO Supernova building in Garching resembles a close binary star exploding as a suoernova (Picture: ESO)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2018\\\/04\\\/26\\\/eroeffnung-eso-supernova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/\",\"name\":\"HITS gGmbH\",\"description\":\"Heidelberg Institute for Theoretical Studies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/86aabe0b57e15165f41adaf38c43d078\",\"name\":\"Lacurie, Isabel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70053c2db6ae031114048dd4c282575b9a4131f66f64abcac683e5f64b3618f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70053c2db6ae031114048dd4c282575b9a4131f66f64abcac683e5f64b3618f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70053c2db6ae031114048dd4c282575b9a4131f66f64abcac683e5f64b3618f4?s=96&d=mm&r=g\",\"caption\":\"Lacurie, Isabel\"},\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/author\\\/hartmail\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet - HITS gGmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/","og_locale":"de_DE","og_type":"article","og_title":"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet - HITS gGmbH","og_description":"Heute wird nach dreij\u00e4hriger Bauzeit das ESO Supernova Planetarium und Besucherzentrum feierlich eingeweiht. Das neue Zentrum am Hauptsitz der Europ\u00e4...","og_url":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/","og_site_name":"HITS gGmbH","article_published_time":"2018-04-26T13:03:28+00:00","article_modified_time":"2019-03-22T08:42:30+00:00","og_image":[{"width":1280,"height":640,"url":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2018\/04\/ann15011b.jpg","type":"image\/jpeg"}],"author":"Lacurie, Isabel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lacurie, Isabel","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/#article","isPartOf":{"@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/"},"author":{"name":"Lacurie, Isabel","@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/86aabe0b57e15165f41adaf38c43d078"},"headline":"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet","datePublished":"2018-04-26T13:03:28+00:00","dateModified":"2019-03-22T08:42:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/"},"wordCount":798,"image":{"@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2018\/04\/ann15011b.jpg","articleSection":["Institutsnews","Pressemitteilungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/","url":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/","name":"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet - HITS gGmbH","isPartOf":{"@id":"https:\/\/www.h-its.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/#primaryimage"},"image":{"@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2018\/04\/ann15011b.jpg","datePublished":"2018-04-26T13:03:28+00:00","dateModified":"2019-03-22T08:42:30+00:00","author":{"@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/86aabe0b57e15165f41adaf38c43d078"},"breadcrumb":{"@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/#primaryimage","url":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2018\/04\/ann15011b.jpg","contentUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2018\/04\/ann15011b.jpg","width":1280,"height":640,"caption":"The ESO Supernova building in Garching resembles a close binary star exploding as a suoernova (Picture: ESO)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.h-its.org\/de\/2018\/04\/26\/eroeffnung-eso-supernova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.h-its.org\/de\/"},{"@type":"ListItem","position":2,"name":"Neues Planetarium und astronomisches Besucherzentrum er\u00f6ffnet"}]},{"@type":"WebSite","@id":"https:\/\/www.h-its.org\/de\/#website","url":"https:\/\/www.h-its.org\/de\/","name":"HITS gGmbH","description":"Heidelberg Institute for Theoretical Studies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.h-its.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/86aabe0b57e15165f41adaf38c43d078","name":"Lacurie, Isabel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/70053c2db6ae031114048dd4c282575b9a4131f66f64abcac683e5f64b3618f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/70053c2db6ae031114048dd4c282575b9a4131f66f64abcac683e5f64b3618f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/70053c2db6ae031114048dd4c282575b9a4131f66f64abcac683e5f64b3618f4?s=96&d=mm&r=g","caption":"Lacurie, Isabel"},"url":"https:\/\/www.h-its.org\/de\/author\/hartmail\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 17:15:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/23587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/comments?post=23587"}],"version-history":[{"count":5,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/23587\/revisions"}],"predecessor-version":[{"id":40275,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/23587\/revisions\/40275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/media\/30196"}],"wp:attachment":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/media?parent=23587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/categories?post=23587"},{"taxonomy":"hits-research-group","embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/hits-research-group?post=23587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}