{"id":46206,"date":"2023-02-15T09:22:12","date_gmt":"2023-02-15T08:22:12","guid":{"rendered":"https:\/\/www.h-its.org\/de\/?p=46206"},"modified":"2026-03-31T13:19:34","modified_gmt":"2026-03-31T11:19:34","slug":"enzymeml","status":"publish","type":"post","link":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/","title":{"rendered":"EnzymeML: Auf der Forschungsdatenwelle surfen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Bei Experimenten zur Katalyse entstehen gro\u00dfe und komplexeDatenmengen. Diese auszuwerten und wieder zu verwenden ist eine enorme Herausforderung. Ein Team von Forschenden und Datenbankspezialist*innen stellt jetzt im Fachjournal \u201eNature Methods\u201c ein Datenaustauschformat vor, das die Ergebnisse enzymatischer Experimente komplett erfasst, die Daten strukturiert ablegt und nachvollziehbar macht. Mit dabei sind auch Wissenschaftler*innen des HITS mit der SABIO-RK-Datenbank, in der kinetische Daten nach der Modellierung direkt gespeichert werden.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend in der Forschung weltweit immer mehr Daten generiert werden, sind diese Datenmengen durch die derzeitige Praxis der Vermittlung wissenschaftlicher Ergebnisse kaum noch zu bew\u00e4ltigen. &nbsp;Fehlende Standards, unvollst\u00e4ndige Metadaten und fehlende Originaldaten machen es fast unm\u00f6glich, publizierte Ergebnisse zu reproduzieren. Dies gilt auch f\u00fcr Studien zur katalytischen Aktivit\u00e4t, Selektivit\u00e4t und Stabilit\u00e4t von Enzymen und enzymatischen Netzwerken, einem Forschungsfeld, das f\u00fcr die industrielle Biotechnologie ebenso von gro\u00dfer Bedeutung ist wie f\u00fcr biomedizinische Fragestellungen. Hinzu kommt, dass Daten zur Beschreibung enzymatischer Experimente besonders komplex sind:&nbsp; Eine enzymatische Reaktion h\u00e4ngt von zahlreichen Faktoren ab, etwa der Proteinsequenz des Enzyms oder dem pH-Wert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoffnung macht nun das neuartige, standardisierte Datenaustauschformat \u201eEnzymeML\u201c, das 23 Autoren*innen aus 14 verschiedenen Forschungseinrichtungen im Fachjournal \u201eNature Methods\u201c vorstellen. EnzymeML kann die Ergebnisse eines enzymatischen Experiments komplett erfassen, von den Reaktionsbedingungen \u00fcber die gemessenen Daten bis zu dem zur Analyse experimenteller Daten verwendeten kinetischen Modell und den gesch\u00e4tzten kinetischen Parametern. Das Format bietet einen nahtlosen Kommunikationskanal zwischen experimentellen Plattformen, elektronischen Laborb\u00fcchern, Werkzeugen zur Modellierung der Enzymkinetik, Ver\u00f6ffentlichungsplattformen und enzymatischen Reaktionsdatenbanken. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Projekt steht unter der Leitung von J\u00fcrgen Pleiss vom Institut f\u00fcr Biochemie und Technische Biochemie der Universit\u00e4t Stuttgart. Die HITS-Wissenschaftler*innen <a href=\"https:\/\/www.h-its.org\/de\/people\/dr-ulrike-wittig\/\">Ulrike Wittig <\/a>und Andreas Weidemann sind im Rahmen von EnzymeML f\u00fcr die Datenintegration zust\u00e4ndig. In der am HITS entwickelten Reaktionsdatenbank \u201eSABIO-RK\u201c \u00a0werden die kinetischen Daten nach der Modellierung direkt gespeichert. Ziel ist es, den gesamten Prozess der Daten vom Experiment im Labor bis zur Speicherung in Datenbanken mit EnzymeML zu unterst\u00fctzen und damit auch die Vollst\u00e4ndigkeit der Daten und deren Qualit\u00e4t von Anfang bis Ende zu gew\u00e4hrleisten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"374\" src=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-1024x374.png\" alt=\"\" class=\"wp-image-46207 wpsmartcrop-image\" srcset=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-1024x374.png 1024w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-300x110.png 300w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-768x281.png 768w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-1536x561.png 1536w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-2048x748.png 2048w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-640x234.png 640w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-1200x438.png 1200w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-1920x701.png 1920w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-3x1.png 3w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-420x153.png 420w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_Pleiss_2-610x223.png 610w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" data-smartcrop-focus=\"[50,50]\" \/><\/a><figcaption class=\"wp-element-caption\">EnzymeML dient als Kommunikationskanal zwischen Experimental-, Modellierungs- und Publikationsplattform. \u00a9 EnzymeML<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ausf\u00fchrlich dazu in der Pressemitteilung der Universit\u00e4t Stuttgart: <a href=\"https:\/\/www.uni-stuttgart.de\/universitaet\/aktuelles\/meldungen\/Auf-der-Forschungsdatenwelle-surfen\/\">https:\/\/www.uni-stuttgart.de\/universitaet\/aktuelles\/meldungen\/Auf-der-Forschungsdatenwelle-surfen\/<\/a><\/em><br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Originalpublikation:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simone Lauterbach, et al.: EnzymeML: seamless data flow and modeling of enzymatic data&#8220;, <a href=\"https:\/\/www.nature.com\/articles\/s41592-022-01763-1\" target=\"_blank\" rel=\"noreferrer noopener\">Nature Methods 2023, DOI 10.1038\/s41592-022-01763-1<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fachlicher Kontakt:<\/strong><br>Universit\u00e4t Stuttgart:<br>Prof. Dr. J\u00fcrgen Pleiss, Institut f\u00fcr Biochemie und Technische Biochemie, Tel.: +49 711 685 63191, E-Mail <a href=\"mailto:juergen.pleiss@itb.uni-stuttgart.de\" target=\"_blank\" rel=\"noreferrer noopener\">juergen.pleiss@itb.uni-stuttgart.de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">HITS:<br><a href=\"https:\/\/www.h-its.org\/de\/people\/dr-ulrike-wittig\/\">Dr. Ulrike Wittig<\/a><br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pressekontakt:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universit\u00e4t Stuttgart:<br>Andrea Mayer-Grenu, Hochschulkommunikation, Tel.: +49 (0)711\/685 82176, E-Mail: a<a href=\"mailto:ndrea.mayer-grenu@hkom.unistuttgart.de\" target=\"_blank\" rel=\"noreferrer noopener\">ndrea.mayer-grenu@hkom.unistuttgart.de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">HITS:<br><a href=\"https:\/\/www.h-its.org\/de\/people\/dr-peter-saueressig\/\">Dr. Peter Saueressig<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei Experimenten zur Katalyse entstehen gro\u00dfe und komplexeDatenmengen. Diese auszuwerten und wieder zu verwenden ist eine enorme Herausforderung. Ein Team &#8230;<\/p>\n","protected":false},"author":58,"featured_media":46208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1,92],"hits-research-group":[1304],"class_list":["post-46206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppen-news","category-wissenschaftsnews","hits-research-group-sdbv-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EnzymeML: Auf der Forschungsdatenwelle surfen - HITS gGmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EnzymeML: Auf der Forschungsdatenwelle surfen - HITS gGmbH\" \/>\n<meta property=\"og:description\" content=\"Bei Experimenten zur Katalyse entstehen gro\u00dfe und komplexeDatenmengen. Diese auszuwerten und wieder zu verwenden ist eine enorme Herausforderung. Ein Team ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/\" \/>\n<meta property=\"og:site_name\" content=\"HITS gGmbH\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-15T08:22:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T11:19:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_enzymML-Logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1026\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Saueressig, Peter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Saueressig, Peter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/\"},\"author\":{\"name\":\"Saueressig, Peter\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/07a50e06406b02a7f4e9506e71f4d0f4\"},\"headline\":\"EnzymeML: Auf der Forschungsdatenwelle surfen\",\"datePublished\":\"2023-02-15T08:22:12+00:00\",\"dateModified\":\"2026-03-31T11:19:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/\"},\"wordCount\":454,\"image\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/06_23_enzymML-Logo.jpg\",\"articleSection\":[\"Gruppen News\",\"Wissenschaftsnews\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/\",\"name\":\"EnzymeML: Auf der Forschungsdatenwelle surfen - HITS gGmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/06_23_enzymML-Logo.jpg\",\"datePublished\":\"2023-02-15T08:22:12+00:00\",\"dateModified\":\"2026-03-31T11:19:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/07a50e06406b02a7f4e9506e71f4d0f4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/06_23_enzymML-Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/06_23_enzymML-Logo.jpg\",\"width\":1026,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2023\\\/02\\\/15\\\/enzymeml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EnzymeML: Auf der Forschungsdatenwelle surfen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/\",\"name\":\"HITS gGmbH\",\"description\":\"Heidelberg Institute for Theoretical Studies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/07a50e06406b02a7f4e9506e71f4d0f4\",\"name\":\"Saueressig, Peter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4ddc446b3883eb8ed21f099e63cdb7222c061e35534dc06b5e5a6376f388f00?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4ddc446b3883eb8ed21f099e63cdb7222c061e35534dc06b5e5a6376f388f00?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4ddc446b3883eb8ed21f099e63cdb7222c061e35534dc06b5e5a6376f388f00?s=96&d=mm&r=g\",\"caption\":\"Saueressig, Peter\"},\"description\":\"hits.ma\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/author\\\/sauerpe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EnzymeML: Auf der Forschungsdatenwelle surfen - HITS gGmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/","og_locale":"de_DE","og_type":"article","og_title":"EnzymeML: Auf der Forschungsdatenwelle surfen - HITS gGmbH","og_description":"Bei Experimenten zur Katalyse entstehen gro\u00dfe und komplexeDatenmengen. Diese auszuwerten und wieder zu verwenden ist eine enorme Herausforderung. Ein Team ...","og_url":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/","og_site_name":"HITS gGmbH","article_published_time":"2023-02-15T08:22:12+00:00","article_modified_time":"2026-03-31T11:19:34+00:00","og_image":[{"width":1026,"height":629,"url":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_enzymML-Logo.jpg","type":"image\/jpeg"}],"author":"Saueressig, Peter","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Saueressig, Peter","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/#article","isPartOf":{"@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/"},"author":{"name":"Saueressig, Peter","@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/07a50e06406b02a7f4e9506e71f4d0f4"},"headline":"EnzymeML: Auf der Forschungsdatenwelle surfen","datePublished":"2023-02-15T08:22:12+00:00","dateModified":"2026-03-31T11:19:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/"},"wordCount":454,"image":{"@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/#primaryimage"},"thumbnailUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_enzymML-Logo.jpg","articleSection":["Gruppen News","Wissenschaftsnews"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/","url":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/","name":"EnzymeML: Auf der Forschungsdatenwelle surfen - HITS gGmbH","isPartOf":{"@id":"https:\/\/www.h-its.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/#primaryimage"},"image":{"@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/#primaryimage"},"thumbnailUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_enzymML-Logo.jpg","datePublished":"2023-02-15T08:22:12+00:00","dateModified":"2026-03-31T11:19:34+00:00","author":{"@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/07a50e06406b02a7f4e9506e71f4d0f4"},"breadcrumb":{"@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/#primaryimage","url":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_enzymML-Logo.jpg","contentUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/06_23_enzymML-Logo.jpg","width":1026,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/www.h-its.org\/de\/2023\/02\/15\/enzymeml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.h-its.org\/de\/"},{"@type":"ListItem","position":2,"name":"EnzymeML: Auf der Forschungsdatenwelle surfen"}]},{"@type":"WebSite","@id":"https:\/\/www.h-its.org\/de\/#website","url":"https:\/\/www.h-its.org\/de\/","name":"HITS gGmbH","description":"Heidelberg Institute for Theoretical Studies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.h-its.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/07a50e06406b02a7f4e9506e71f4d0f4","name":"Saueressig, Peter","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f4ddc446b3883eb8ed21f099e63cdb7222c061e35534dc06b5e5a6376f388f00?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4ddc446b3883eb8ed21f099e63cdb7222c061e35534dc06b5e5a6376f388f00?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4ddc446b3883eb8ed21f099e63cdb7222c061e35534dc06b5e5a6376f388f00?s=96&d=mm&r=g","caption":"Saueressig, Peter"},"description":"hits.ma","url":"https:\/\/www.h-its.org\/de\/author\/sauerpe\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 13:37:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/46206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/comments?post=46206"}],"version-history":[{"count":2,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/46206\/revisions"}],"predecessor-version":[{"id":50670,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/46206\/revisions\/50670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/media\/46208"}],"wp:attachment":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/media?parent=46206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/categories?post=46206"},{"taxonomy":"hits-research-group","embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/hits-research-group?post=46206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}