{"id":50353,"date":"2026-01-15T15:40:28","date_gmt":"2026-01-15T14:40:28","guid":{"rendered":"https:\/\/www.h-its.org\/de\/?p=50353"},"modified":"2026-01-15T15:53:00","modified_gmt":"2026-01-15T14:53:00","slug":"von-form-zu-form-die-dynamische-welt-der-proteine","status":"publish","type":"post","link":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/","title":{"rendered":"Von Form zu Form: die dynamische Welt der Proteine"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Im Juli 2025 entwickelten Forscher*innen des Heidelberger Instituts f\u00fcr Theoretische Studien (HITS) und des Max-Planck-Instituts f\u00fcr Polymerforschung (MPIP) ein Modell, das Proteine mit individuell anpassbarer Flexibilit\u00e4t entwerfen kann. Ein neues, erg\u00e4nzendes Deep-Learning-Modell \u2013 Back Bone Flow (BBFlow) \u2013 kann nun die Dynamik von Proteinen vorhersagen und damit Einblicke in ihre Funktionsweise liefern. Die Ergebnisse wurden im Dezember 2025 auf internationalen Fachkonferenzen in San Diego und Kopenhagen vorgestellt.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anders als die bereits bestehenden Modelle <a href=\"https:\/\/www.h-its.org\/projects\/gafl\/\" target=\"_blank\" rel=\"noreferrer noopener\">GAFL (Geometric Algebra Flow Matching)<\/a> und <a href=\"https:\/\/www.h-its.org\/de\/2025\/07\/23\/flips-mli\/\" target=\"_blank\" rel=\"noreferrer noopener\">FliPS (Flexibility-Conditioned Protein Structure Design with Flow Matching)<\/a> kann dieses Flow-basierte Deep-Learning-Modell die dreidimensionale Struktur eines Proteins allein anhand der Geometrie des R\u00fcckgrats \u2013 der Hauptkette der Atome \u2013 erfassen. Bei klassischen Ans\u00e4tzen werden daf\u00fcr komplexe Simulationen oder evolution\u00e4re Sequenzdaten ben\u00f6tigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eW\u00e4hrend BBFlow die Proteindynamik vorhersagt, generiert FliPS neue Proteine mit der gew\u00fcnschten Dynamik. BBFlow kann dann die besten von FliPS generierten Kandidaten herausfiltern\u201c, sagt <a href=\"https:\/\/www.h-its.org\/de\/people\/nicolas-wolf\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nicolas Wolf<\/a>, Erstautor der <a href=\"https:\/\/arxiv.org\/pdf\/2503.05738\" target=\"_blank\" rel=\"noreferrer noopener\">Studie<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus ist BBFlow leicht zug\u00e4nglich, intuitiv bedienbar und erfordert keinerlei Programmierkenntnisse. Gleichzeitig arbeitet es bis zu 40-mal schneller als das derzeit f\u00fchrende Modell \u201eAlphaFlow\u201c \u2013 bei vergleichbarer Genauigkeit. Da das Modell keine evolution\u00e4ren Daten ben\u00f6tigt, eignet es sich besonders f\u00fcr neue oder synthetische Proteine, f\u00fcr die es keine nat\u00fcrlichen Vorbilder gibt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schnell, effizient und pr\u00e4zise: eine Bandbreite an Ensembles<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist vor allem diese hohe Geschwindigkeit, mit der BBFlow punkten kann. Das Modell l\u00e4sst sich in wenigen Tagen von Grund auf trainieren, ohne aufw\u00e4ndiges Pre-Training oder evolution\u00e4re Informationen. Tests zeigen, dass es realistische Ensembles sowohl f\u00fcr nat\u00fcrlich vorkommende als auch f\u00fcr neu entworfene (de novo) Proteine erzeugt \u2013 auch wenn f\u00fcr diese Proteine keine evolution\u00e4ren Daten vorliegen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"423\" src=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-1024x423.png\" alt=\"\" class=\"wp-image-50363\" srcset=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-1024x423.png 1024w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-300x124.png 300w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-768x318.png 768w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-1536x635.png 1536w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-2048x847.png 2048w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-640x265.png 640w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-1200x496.png 1200w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-1920x794.png 1920w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-2x1.png 2w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-420x174.png 420w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/BBFlow-1-610x252.png 610w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" \/><figcaption class=\"wp-element-caption\">BBflow beginnt mit der normalen Struktur eines Proteins und sagt nach und nach voraus, wie sich sein R\u00fcckgrat bewegen kann, indem zuf\u00e4lliges Rauschen in realistische Formen verwandelt wird, die von der urspr\u00fcnglichen Proteinstruktur geleitet werden. (Abbildung aus der Publikation)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eStatt auf evolution\u00e4re Daten zu setzen, nutzen wir jetzt eine Methode, die Proteinstrukturen direkt erzeugt. Dabei verwenden wir die bekannte Ausgangsstruktur des Proteins, um das Modell zu steuern\u201c, sagt <a href=\"https:\/\/www.h-its.org\/de\/people\/leif-seute\/\" target=\"_blank\" rel=\"noreferrer noopener\">Leif Seute<\/a>, Doktorand in der Forschungsgruppe Machine Learning and Artificial Intelligence (MLI) und Zweitautor der Studie. Das Ergebnis: deutlich schnellere Vorhersagen bei vergleichbarer Genauigkeit. \u201eDie Methode funktioniert nicht nur f\u00fcr nat\u00fcrliche monomere Proteine, sondern auch f\u00fcr de novo und multimerische Proteine\u201c, f\u00fcgt Seute hinzu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"657\" src=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-1024x657.png\" alt=\"\" class=\"wp-image-50355\" srcset=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-1024x657.png 1024w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-300x193.png 300w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-768x493.png 768w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-1536x986.png 1536w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-2048x1315.png 2048w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-640x411.png 640w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-1200x770.png 1200w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-1920x1232.png 1920w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-2x1.png 2w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-420x270.png 420w, https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/bbflow_samples_transparent-610x392.png 610w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" \/><figcaption class=\"wp-element-caption\">Von BBFlow vorhergesagte Protein-Ensembles. Die dargestellten Proteine wurden mit den Programmen RFDiffusion und ProteinMPNN generiert und sind farblich nach der Position ihrer Bausteine dargestellt.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Ansatz k\u00f6nnte die Protein-Forschung und das Design neuer Proteine erheblich beschleunigen \u2013 ein wichtiger Schritt f\u00fcr die Entwicklung neuer Medikamente, Therapien und Materialien. Statt nur eine einzige \u201efunktionale Form\u201c zu liefern, erzeugt BBFlow ein ganzes Ensemble m\u00f6glicher Strukturen, was die Flexibilit\u00e4t von Proteinen realistischer abbildet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ein Schritt hin zu authentischen Proteinmodellen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indem der Fokus von starren Einzelstrukturen auf dynamische Ensembles verschoben wird, kommen die Forscher*innen der Frage n\u00e4her, wie Proteine tats\u00e4chlich in der Zelle agieren. Auch wenn das aktuelle Modell sich bisher auf das R\u00fcckgrat beschr\u00e4nkt und noch nicht alle Atome und Seitenketten einbezieht, zeigt es: die R\u00fcckgratgeometrie allein liefert wesentlich mehr Informationen als bislang angenommen. Es er\u00f6ffnet eine neue Perspektive, in der Wirklichkeitstreue, Geschwindigkeit und Flexibilit\u00e4t beim Protein-Design nicht l\u00e4nger im Widerspruch stehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N. Wolf, L. Seute, V. Viliuga, S. Wagner, J. St\u00fchmer, F. Gr\u00e4ter. Learning conformational ensembles of proteins based on backbone geometry. NeurIPS, 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wissenschaftlicher Kontakt:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jun.-Prof. Dr. Jan St\u00fchmer<br>Junior Group Leader<br>Machine Learning and Artificial Intelligence<br>Heidelberger Institut f\u00fcr Theoretische Studien (HITS)<br>https:\/\/www.h-its.org\/de\/people\/dr-jan-stuhmer\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prof. Dr. Frauke Gr\u00e4ter<br>Director, Abteilungsleiterin \u201cBiomolekulare Mechanik\u201d<br>Max-Planck-Institut f\u00fcr Polymerforschung (MPIP)<br>https:\/\/www.mpip-mainz.mpg.de\/1001466\/01_Direktor<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Medienkontakt:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Angela Michel<br>Head of Communications<br>Heidelberger Institut f\u00fcr Theoretische Studien (HITS)<br>+49 (0)6221 533 277<br>angela.michel@h-its.org<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teresa Petry<br>Presse- und \u00d6ffentlichkeitsarbeit<br>Max-Planck-Institut f\u00fcr Polymerforschung (MPIP)<br>+49 (0)6131 379-119<br>pr@mpip-mainz.mpg.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Juli 2025 entwickelten Forscher*innen des Heidelberger Instituts f\u00fcr Theoretische Studien (HITS) und des Max-Planck-Instituts f\u00fcr Polymerforschung (MPIP) ein &#8230;<\/p>\n","protected":false},"author":156,"featured_media":50359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"hits-research-group":[],"class_list":["post-50353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppen-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von Form zu Form: die dynamische Welt der Proteine - HITS gGmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von Form zu Form: die dynamische Welt der Proteine - HITS gGmbH\" \/>\n<meta property=\"og:description\" content=\"Im Juli 2025 entwickelten Forscher*innen des Heidelberger Instituts f\u00fcr Theoretische Studien (HITS) und des Max-Planck-Instituts f\u00fcr Polymerforschung (MPIP) ein ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/\" \/>\n<meta property=\"og:site_name\" content=\"HITS gGmbH\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-15T14:40:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T14:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/hits-pattern-70-1024x760.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"almeidma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"almeidma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/\"},\"author\":{\"name\":\"almeidma\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/764b157ffbf22741705e7ffb3fddd862\"},\"headline\":\"Von Form zu Form: die dynamische Welt der Proteine\",\"datePublished\":\"2026-01-15T14:40:28+00:00\",\"dateModified\":\"2026-01-15T14:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/\"},\"wordCount\":676,\"image\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/hits-pattern-70-scaled.png\",\"articleSection\":[\"Gruppen News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/\",\"name\":\"Von Form zu Form: die dynamische Welt der Proteine - HITS gGmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/hits-pattern-70-scaled.png\",\"datePublished\":\"2026-01-15T14:40:28+00:00\",\"dateModified\":\"2026-01-15T14:53:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/764b157ffbf22741705e7ffb3fddd862\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/hits-pattern-70-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/01\\\/hits-pattern-70-scaled.png\",\"width\":2560,\"height\":1899},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/2026\\\/01\\\/15\\\/von-form-zu-form-die-dynamische-welt-der-proteine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von Form zu Form: die dynamische Welt der Proteine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/\",\"name\":\"HITS gGmbH\",\"description\":\"Heidelberg Institute for Theoretical Studies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/#\\\/schema\\\/person\\\/764b157ffbf22741705e7ffb3fddd862\",\"name\":\"almeidma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99c5db721b6717762969f0614b028cbe756602066b690d9d1bb890bb499d3b69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99c5db721b6717762969f0614b028cbe756602066b690d9d1bb890bb499d3b69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99c5db721b6717762969f0614b028cbe756602066b690d9d1bb890bb499d3b69?s=96&d=mm&r=g\",\"caption\":\"almeidma\"},\"url\":\"https:\\\/\\\/www.h-its.org\\\/de\\\/author\\\/almeidma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von Form zu Form: die dynamische Welt der Proteine - HITS gGmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/","og_locale":"de_DE","og_type":"article","og_title":"Von Form zu Form: die dynamische Welt der Proteine - HITS gGmbH","og_description":"Im Juli 2025 entwickelten Forscher*innen des Heidelberger Instituts f\u00fcr Theoretische Studien (HITS) und des Max-Planck-Instituts f\u00fcr Polymerforschung (MPIP) ein ...","og_url":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/","og_site_name":"HITS gGmbH","article_published_time":"2026-01-15T14:40:28+00:00","article_modified_time":"2026-01-15T14:53:00+00:00","og_image":[{"width":1024,"height":760,"url":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/hits-pattern-70-1024x760.png","type":"image\/png"}],"author":"almeidma","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"almeidma","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/#article","isPartOf":{"@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/"},"author":{"name":"almeidma","@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/764b157ffbf22741705e7ffb3fddd862"},"headline":"Von Form zu Form: die dynamische Welt der Proteine","datePublished":"2026-01-15T14:40:28+00:00","dateModified":"2026-01-15T14:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/"},"wordCount":676,"image":{"@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/hits-pattern-70-scaled.png","articleSection":["Gruppen News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/","url":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/","name":"Von Form zu Form: die dynamische Welt der Proteine - HITS gGmbH","isPartOf":{"@id":"https:\/\/www.h-its.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/#primaryimage"},"image":{"@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/hits-pattern-70-scaled.png","datePublished":"2026-01-15T14:40:28+00:00","dateModified":"2026-01-15T14:53:00+00:00","author":{"@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/764b157ffbf22741705e7ffb3fddd862"},"breadcrumb":{"@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/#primaryimage","url":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/hits-pattern-70-scaled.png","contentUrl":"https:\/\/www.h-its.org\/de\/wp-content\/uploads\/sites\/2\/2026\/01\/hits-pattern-70-scaled.png","width":2560,"height":1899},{"@type":"BreadcrumbList","@id":"https:\/\/www.h-its.org\/de\/2026\/01\/15\/von-form-zu-form-die-dynamische-welt-der-proteine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.h-its.org\/de\/"},{"@type":"ListItem","position":2,"name":"Von Form zu Form: die dynamische Welt der Proteine"}]},{"@type":"WebSite","@id":"https:\/\/www.h-its.org\/de\/#website","url":"https:\/\/www.h-its.org\/de\/","name":"HITS gGmbH","description":"Heidelberg Institute for Theoretical Studies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.h-its.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.h-its.org\/de\/#\/schema\/person\/764b157ffbf22741705e7ffb3fddd862","name":"almeidma","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/99c5db721b6717762969f0614b028cbe756602066b690d9d1bb890bb499d3b69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99c5db721b6717762969f0614b028cbe756602066b690d9d1bb890bb499d3b69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99c5db721b6717762969f0614b028cbe756602066b690d9d1bb890bb499d3b69?s=96&d=mm&r=g","caption":"almeidma"},"url":"https:\/\/www.h-its.org\/de\/author\/almeidma\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:54:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/50353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/users\/156"}],"replies":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/comments?post=50353"}],"version-history":[{"count":6,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/50353\/revisions"}],"predecessor-version":[{"id":50366,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/posts\/50353\/revisions\/50366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/media\/50359"}],"wp:attachment":[{"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/media?parent=50353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/categories?post=50353"},{"taxonomy":"hits-research-group","embeddable":true,"href":"https:\/\/www.h-its.org\/de\/wp-json\/wp\/v2\/hits-research-group?post=50353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}